{"id":23783,"date":"2022-02-02T01:36:38","date_gmt":"2022-02-02T05:36:38","guid":{"rendered":"http:\/\/osteomag.ca\/?p=23783"},"modified":"2026-02-18T06:06:29","modified_gmt":"2026-02-18T11:06:29","slug":"dechirure-quadriceps","status":"publish","type":"post","link":"https:\/\/osteomag.ca\/fr\/dechirure-quadriceps\/","title":{"rendered":"D\u00e9chirure des quadriceps"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/osteomag.ca\/fr\/dechirure-quadriceps\/#Facteurs_risques\" >Facteurs risques<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/osteomag.ca\/fr\/dechirure-quadriceps\/#Causes\" >Causes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/osteomag.ca\/fr\/dechirure-quadriceps\/#Symptomes\" >Sympt\u00f4mes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/osteomag.ca\/fr\/dechirure-quadriceps\/#Classification_pour_les_etirements_du_quadriceps\" >Classification pour les \u00e9tirements du quadriceps<\/a><\/li><\/ul><\/nav><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;23783&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;D\u00e9chirure des quadriceps&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background wp-block-paragraph\">Les quatre quadriceps sont impliqu\u00e9s dans la marche, la course, et le redressement et la flexion de la jambe. Ils sont tous sensibles aux blessures, tout comme les tendons de la cuisse. La gravit\u00e9 des blessures \u00e0 ces muscles varie des contusions (ecchymoses), des foulures (petites d\u00e9chirures) du tendon ou du muscle, aux ruptures (d\u00e9chirures compl\u00e8tes).<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"facteurs-risques\"><span class=\"ez-toc-section\" id=\"Facteurs_risques\"><\/span>Facteurs risques<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Avoir des muscles fatigu\u00e9s<\/li><li>Surcharger les muscles des jambes<\/li><li>Football ou le soccer<\/li><li>Mauvais r\u00e9chauffement avant exercice<\/li><li>Les muscles quadriceps faibles sont plus susceptibles de se d\u00e9chirer. <ul><li>Tendinite dans le quadriceps<\/li><li>Utiliser des st\u00e9ro\u00efdes<\/li><li>\u00catre s\u00e9dentaire pendant de longues p\u00e9riodes<\/li><li>Avoir certaines maladies chroniques qui perturbent la circulation sanguine<\/li><\/ul><\/li><\/ul>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"causes\"><span class=\"ez-toc-section\" id=\"Causes\"><\/span>Causes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Des mouvements brusques et puissants de la jambe peuvent provoquer une d\u00e9chirure ou une tension du muscle quadriceps. Ces mouvements peuvent survenir \u00e0 la suite d&rsquo;un \u00e9tirement excessif du muscle ou lors de la pratique de sports tels que le football ou le soccer.<gwmw style=\"display:none;\"><gwmw style=\"display:none;\"><\/gwmw><\/gwmw><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"symptomes\"><span class=\"ez-toc-section\" id=\"Symptomes\"><\/span>Sympt\u00f4mes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Douleur et gonflement de la cuisse<\/li><li>Inflammation ou ecchymose visible<\/li><li>Difficult\u00e9 \u00e0 plier et redresser le genou<\/li><li>Faiblesse des jambes et amplitude de mouvement r\u00e9duite<\/li><li>Douleur aigu\u00eb en courant, en sautant ou en donnant des coups de pied<\/li><\/ul>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"classification-pour-les-etirements-du-quadriceps\"><span class=\"ez-toc-section\" id=\"Classification_pour_les_etirements_du_quadriceps\"><\/span>Classification pour les \u00e9tirements du quadriceps<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div><\/div>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>L\u00e9ger<\/strong> : D\u00e9chirure mineure des fibres musculaires avec peu ou pas de perte de force. La douleur est g\u00e9n\u00e9ralement l\u00e9g\u00e8re \u00e0 mod\u00e9r\u00e9e, sans d\u00e9faut palpable dans le tissu musculaire \u00e0 l&rsquo;examen.<\/li><li><strong>Mod\u00e9r\u00e9<\/strong> : Perturbation plus grave des fibres musculaires avec une douleur et une perte de force importantes. Un d\u00e9faut dans le tissu musculaire peut parfois \u00eatre ressenti.<\/li><li><strong>S\u00e9v\u00e8re <\/strong>: D\u00e9chirure compl\u00e8te du muscle associ\u00e9e \u00e0 une douleur intense et \u00e0 une perte totale de force. Un d\u00e9faut palpable dans le tissu musculaire peut fr\u00e9quemment \u00eatre ressenti, en particulier s&rsquo;il est examin\u00e9 au d\u00e9but de la blessure avant la formation d&rsquo;un h\u00e9matome.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Les quatre quadriceps sont impliqu\u00e9s dans la marche, la course, et le redressement et la flexion de la jambe. Ils sont tous sensibles aux blessures, tout comme les tendons de la cuisse. La gravit\u00e9 des blessures \u00e0 ces muscles varie des contusions (ecchymoses), des foulures (petites d\u00e9chirures) du tendon ou du muscle, aux ruptures (d\u00e9chirures compl\u00e8tes).<\/p>\n","protected":false},"author":1,"featured_media":55171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","iawp_total_views":3,"footnotes":""},"categories":[330,344,321],"tags":[],"class_list":["post-23783","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cuisse","category-dechirure-musculaire","category-dechirure-tendon"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/posts\/23783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/comments?post=23783"}],"version-history":[{"count":0,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/posts\/23783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/media\/55171"}],"wp:attachment":[{"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/media?parent=23783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/categories?post=23783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osteomag.ca\/fr\/wp-json\/wp\/v2\/tags?post=23783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}